{"id":3141,"date":"2023-05-08T10:31:29","date_gmt":"2023-05-08T10:31:29","guid":{"rendered":"https:\/\/hotel-life.hr\/soggiorno\/"},"modified":"2026-07-22T13:56:40","modified_gmt":"2026-07-22T13:56:40","slug":"soggiorno","status":"publish","type":"page","link":"https:\/\/hotel-life.hr\/it\/soggiorno\/","title":{"rendered":"Soggiorno"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3141\" class=\"elementor elementor-3141 elementor-1418\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dbf8e9 elementor-section-height-min-height cs-section-content-fullwidth cs-parallax-on-scroll cs_scroll_y_80 elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9dbf8e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"80\" style=\"background-image: none;\" data-cs-background-image=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/HotelLifeRooms.jpg\" data-cs-background-image-alt-text=\"hotel Life Rogoznica Croazia\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-105b500 dark-color\" data-id=\"105b500\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f599258 elementor-widget elementor-widget-cs_title\" data-id=\"f599258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">Le Nostre Sistemazioni<\/span><\/div>\t            <h1 class=\"cs-title\">\n\t                Camere &amp; Suite\t            <\/h1>\t            <div class=\"cs-title-text\">\n\t                <p>Goditi un soggiorno rilassante a Rogoznica con camere eleganti, comfort moderno e splendide viste sul mare Adriatico.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a35d5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a35d5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86ac464 dark-color\" data-id=\"86ac464\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e6d28c elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"1e6d28c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div>\r\n\r\n\r\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\r\n\r\n<!-- Add jQuery library -->\r\n<script src=\"https:\/\/code.jquery.com\/jquery-3.6.0.min.js\"><\/script>\r\n\r\n<!-- Add jQuery UI library -->\r\n<script src=\"https:\/\/code.jquery.com\/ui\/1.13.1\/jquery-ui.min.js\"><\/script>\r\n\r\n<!-- Add jQuery UI CSS -->\r\n<link rel=\"stylesheet\" href=\"https:\/\/code.jquery.com\/ui\/1.13.1\/themes\/base\/jquery-ui.css\">\r\n\r\n<style>\r\n\r\n   input[type=\"text\"] {\r\n      color: white;\r\n      font-family: 'Marcellus', serif;\r\n      border: 1px solid #B99D75;\r\n      padding: 15px;\r\n      box-sizing: border-box;\r\n   }\r\n\r\n   input[type=\"text\"]::placeholder {\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   input[type=\"text\"]::-webkit-input-placeholder {\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   input[type=\"text\"]:-ms-input-placeholder {\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   input[type=\"text\"]::-ms-input-placeholder {\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   .content-container {\r\n      display: flex;\r\n      justify-content: center;\r\n      align-items: center;\r\n      background-color: #01636F;\r\n      padding: 25px;\r\n   }\r\n\r\n   .date-container {\r\n      display: flex;\r\n      justify-content: center;\r\n      align-items: center;\r\n      gap: 25px;\r\n   }\r\n\r\n   .button1 {\r\n      \/* Add button styles here if needed *\/\r\n   }\r\n\r\n<\/style>\r\n\r\n\r\n\r\n\r\n<!-- PHOBS \/\/ start -->\r\n<form id=\"phobs_book\">\r\n\r\n   <input name=\"hotel\" type=\"hidden\" value=\"5996245b13cea4b40b1f0e58dee0ba6f\" style=\"display:none\">\r\n\r\n   <div class=\"content-container\">\r\n      <div class=\"date-container\">\r\n\r\n         <input type=\"text\" id=\"datepicker1\" name=\"arrival_date\" placeholder=\"Data di Check In\">\r\n\r\n         <input type=\"text\" id=\"datepicker2\" name=\"checkout_date\" placeholder=\"Data di Check Out\">\r\n\r\n         <input type=\"text\" id=\"promo_code\" name=\"promo_code\" placeholder=\"Codice Promozionale\">\r\n\r\n         <input type=\"submit\" value=\"Prenota Direttamente & Risparmia\" class=\"button1\">\r\n\r\n      <\/div>\r\n   <\/div>\r\n\r\n   <input name=\"company_id\" type=\"hidden\" value=\"740febbade51b20e3fc659f3a57f496d\" style=\"display:none\">\r\n   <input name=\"lang\" type=\"hidden\" value=\"en\" style=\"display:none\">\r\n\r\n<\/form>\r\n\r\n<script>\r\n\r\n   $(function() {\r\n      $(\"#datepicker1\").datepicker({ dateFormat: 'dd\/mm\/yy' });\r\n      $(\"#datepicker2\").datepicker({ dateFormat: 'dd\/mm\/yy' });\r\n   });\r\n\r\n   $(\"#phobs_book\").submit(function (event) {\r\n\r\n      event.preventDefault();\r\n\r\n      var arrivalDate = $(\"#datepicker1\").datepicker(\"getDate\");\r\n      var checkoutDate = $(\"#datepicker2\").datepicker(\"getDate\");\r\n\r\n      var oneDay = 24 * 60 * 60 * 1000;\r\n      var nights = Math.round(Math.abs((checkoutDate - arrivalDate) \/ oneDay));\r\n\r\n      if (arrivalDate >= checkoutDate) {\r\n         alert(\"Checkout date must be after the check-in date.\");\r\n         return;\r\n      }\r\n\r\n      var formattedArrivalDate = formatDateForPhobs(arrivalDate);\r\n\r\n      var promoCode = $(\"#promo_code\").val().trim();\r\n      var promoCodeParam = promoCode ? \"&partners_access=\" + encodeURIComponent(promoCode) : \"\";\r\n\r\n      var url = \"https:\/\/secure.phobs.net\/book.php?\";\r\n      url += \"company_id=740febbade51b20e3fc659f3a57f496d\";\r\n      url += \"&hotel=5996245b13cea4b40b1f0e58dee0ba6f\";\r\n      url += \"&date=\" + formattedArrivalDate;\r\n      url += \"&nights=\" + nights;\r\n      url += \"&lang=en\";\r\n      url += promoCodeParam;\r\n\r\n      window.location.href = url;\r\n\r\n   });\r\n\r\n   function formatDateForPhobs(date) {\r\n\r\n      var day = date.getDate();\r\n      var month = date.getMonth() + 1;\r\n      var year = date.getFullYear();\r\n\r\n      if (day < 10) {\r\n         day = '0' + day;\r\n      }\r\n\r\n      if (month < 10) {\r\n         month = '0' + month;\r\n      }\r\n\r\n      return year + \"-\" + month + \"-\" + day;\r\n   }\r\n\r\n<\/script>\r\n\r\n\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee1046 elementor-hidden-desktop elementor-widget elementor-widget-html\" data-id=\"6ee1046\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div>\r\n\r\n\r\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\r\n<!-- Add jQuery library -->\r\n<script src=\"https:\/\/code.jquery.com\/jquery-3.6.0.min.js\"><\/script>\r\n<!-- Add jQuery UI library -->\r\n<script src=\"https:\/\/code.jquery.com\/ui\/1.13.1\/jquery-ui.min.js\"><\/script>\r\n<!-- Add jQuery UI CSS -->\r\n<link rel=\"stylesheet\" href=\"https:\/\/code.jquery.com\/ui\/1.13.1\/themes\/base\/jquery-ui.css\">\r\n<style>\r\n   \/* Reset default styles *\/\r\n   input[type=\"text\"].mobile-input {\r\n      color: white; \/* Set text color to white *\/\r\n      font-family: 'Marcellus', serif; \/* Set font family *\/\r\n      border: 1px solid #B99D75; \/* Set border color *\/\r\n      padding: 15px;\r\n      box-sizing: border-box;\r\n      width: 100%; \/* Full width for mobile *\/\r\n   }\r\n\r\n   \/* Placeholder text color *\/\r\n   input[type=\"text\"].mobile-input::placeholder { \/* Modern browsers *\/\r\n      color: white;\r\n      opacity: 1; \/* Remove default opacity *\/\r\n   }\r\n\r\n   input[type=\"text\"].mobile-input::-webkit-input-placeholder { \/* WebKit browsers *\/\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   input[type=\"text\"].mobile-input:-ms-input-placeholder { \/* Internet Explorer 10-11 *\/\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   input[type=\"text\"].mobile-input::-ms-input-placeholder { \/* Microsoft Edge *\/\r\n      color: white;\r\n      opacity: 1;\r\n   }\r\n\r\n   \/* Specific styles for the mobile form *\/\r\n   .content-container-mobile {\r\n      display: flex;\r\n      flex-direction: column;\r\n      align-items: center;\r\n      background-color: #01636F !important;\r\n      padding: 25px;\r\n   }\r\n\r\n   .date-container-mobile {\r\n      display: flex;\r\n      flex-direction: column;\r\n      align-items: center;\r\n      gap: 15px;\r\n      width: 100%;\r\n   }\r\n\r\n   .button1-mobile {\r\n      padding: 15px;\r\n      font-size: 16px;\r\n      background-color: #B99D75;\r\n      color: white;\r\n      border: none;\r\n      cursor: pointer;\r\n      width: 100%; \/* Full width for mobile *\/\r\n   }\r\n<\/style>\r\n\r\n\r\n<!-- PHOBS \/\/ start -->\r\n<form id=\"phobs_book_mobile\">\r\n   <input name=\"hotel\" type=\"hidden\" value=\"5996245b13cea4b40b1f0e58dee0ba6f\" style=\"display: none\">\r\n   <div class=\"content-container-mobile\" style=\"background-color: #00455B !important;\">\r\n      <div class=\"date-container-mobile\">\r\n         <input type=\"text\" id=\"datepicker1-mobile\" class=\"mobile-input\" name=\"arrival_date\" placeholder=\"Data di Check In\">\r\n         <input type=\"text\" id=\"datepicker2-mobile\" class=\"mobile-input\" name=\"checkout_date\" placeholder=\"Data di Check Out\">\r\n         <input type=\"text\" id=\"promo_code-mobile\" class=\"mobile-input\" name=\"promo_code\" placeholder=\"Codice Promozionale\">\r\n         <input type=\"submit\" value=\"Prenota Direttamente & Risparmia\" class=\"button1-mobile\">\r\n      <\/div>\r\n   <\/div>\r\n   <input name=\"company_id\" type=\"hidden\" value=\"740febbade51b20e3fc659f3a57f496d\" style=\"display: none\">\r\n   <input name=\"lang\" type=\"hidden\" value=\"en\" style=\"display: none\">\r\n<\/form>\r\n<script>\r\n   \/\/ JavaScript code for datepicker integration\r\n   $(function() {\r\n      $(\"#datepicker1-mobile\").datepicker({ dateFormat: 'dd\/mm\/yy' });\r\n      $(\"#datepicker2-mobile\").datepicker({ dateFormat: 'dd\/mm\/yy' });\r\n   });\r\n\r\n   \/\/ Ensure proper date format before form submission\r\n   $(\"#phobs_book_mobile\").submit(function (event) {\r\n      \/\/ Prevent the default form submission\r\n      event.preventDefault();\r\n\r\n      \/\/ Get selected arrival and checkout dates\r\n      var arrivalDate = $(\"#datepicker1-mobile\").datepicker(\"getDate\");\r\n      var checkoutDate = $(\"#datepicker2-mobile\").datepicker(\"getDate\");\r\n\r\n      \/\/ Calculate the number of nights\r\n      var oneDay = 24 * 60 * 60 * 1000; \/\/ hours*minutes*seconds*milliseconds\r\n      var nights = Math.round(Math.abs((checkoutDate - arrivalDate) \/ oneDay));\r\n\r\n      \/\/ Check if the checkout date is before the check-in date\r\n      if (arrivalDate >= checkoutDate) {\r\n         \/\/ Handle the error, maybe show a message to the user\r\n         alert(\"Check Out date must be after the Check In date.\");\r\n         return; \/\/ Exit the function, do not proceed with URL construction\r\n      }\r\n\r\n      \/\/ Format arrival date as YYYY-MM-DD\r\n      var formattedArrivalDate = formatDateForPhobs(arrivalDate);\r\n      var formattedCheckoutDate = formatDateForPhobs(checkoutDate);\r\n\r\n      \/\/ Get promo code value\r\n      var promoCode = $(\"#promo_code-mobile\").val().trim();\r\n      var promoCodeParam = promoCode ? \"&partners_access=\" + encodeURIComponent(promoCode) : \"\";\r\n\r\n      \/\/ Construct the URL with correct dates, nights, and promo code if available\r\n      var url = \"https:\/\/secure.phobs.net\/book.php?\";\r\n      url += \"company_id=740febbade51b20e3fc659f3a57f496d\";\r\n      url += \"&hotel=5996245b13cea4b40b1f0e58dee0ba6f\";\r\n      url += \"&date=\" + formattedArrivalDate;\r\n      url += \"&nights=\" + nights;\r\n      url += \"&lang=en\";\r\n      url += promoCodeParam;\r\n\r\n      \/\/ Redirect to the updated URL\r\n      window.location.href = url;\r\n   });\r\n\r\n   \/\/ Function to format date as YYYY-MM-DD for Phobs\r\n   function formatDateForPhobs(date) {\r\n      var day = date.getDate();\r\n      var month = date.getMonth() + 1;\r\n      var year = date.getFullYear();\r\n\r\n      \/\/ Ensure leading zeros for day and month\r\n      if (day < 10) {\r\n         day = '0' + day;\r\n      }\r\n      if (month < 10) {\r\n         month = '0' + month;\r\n      }\r\n\r\n      return year + \"-\" + month + \"-\" + day;\r\n   }\r\n<\/script>\r\n\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10e74de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10e74de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf172eb\" data-id=\"bf172eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb2fa9b elementor-widget elementor-widget-cs_title\" data-id=\"fb2fa9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Inizia il Tuo Soggiorno Confortevole<\/span><\/div>\t            <h5 class=\"cs-title\">\n\t                Trova la Camera Perfetta per il Tuo Soggiorno\t            <\/h5>\t            <div class=\"cs-title-text\">\n\t                <p>Scopri 19 camere e suite elegantemente progettate nell&#8217;ambiente tranquillo della Baia di Ze\u010devo vicino a Rogoznica. Dalle confortevoli Superior Room alle spaziose Junior Suite, alle esclusive Life Suite e alla Family Suite, ogni sistemazione \u00e8 progettata per offrire comfort, privacy e una rilassante fuga adriatica. La maggior parte delle camere dispone di balcone privato e splendide viste sul mare o vista laterale sul mare, creando l&#8217;ambiente perfetto per un soggiorno indimenticabile.  <\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b558cc cs-section-content-fullwidth elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b558cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7e1fa0\" data-id=\"a7e1fa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14cc592 elementor-invisible elementor-widget elementor-widget-cs_info_box\" data-id=\"14cc592\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"cs_info_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"cs-info-box column-3 valign-middle img-left\">\n                <div class=\"cs-info-box-wrap\">                    <div class=\"cs-info-box-item elementor-repeater-item-6460937\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-review\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Sistemazione boutique nella tranquilla Baia di Ze\u010devo vicino a Rogoznica, ideale per una rilassante fuga adriatica.<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-e253a92\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-sunrise\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Svegliati con splendide viste sul mare o vista laterale sul mare da camere e suite elegantemente progettate con balconi privati.<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-03432c7\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-bathtub-5\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Tutte le camere dispongono di bagno privato, servizi premium e tutto il necessario per un soggiorno confortevole.<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-6d9a7a6\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-cocktail-1\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Goditi l'aria fresca mediterranea e l'ambiente tranquillo dal tuo balcone privato.<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-be97d74\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-customer-service\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Scegli tra Superior Room, Junior Suite, Life Suite e una spaziosa Family Suite.<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-957a5a7\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-massage\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Articoli da toeletta gratuiti, Wi-Fi gratuito, aria condizionata e servizio attento sono inclusi durante tutto il tuo soggiorno.<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cd1ecf cs-animation-small-offset elementor-invisible elementor-widget elementor-widget-cs_rooms\" data-id=\"8cd1ecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"cs_rooms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"posts cs-rooms text-center layout-zigzag layout-list img-ratio-3-2\" data-settings='{\"query\":{\"paged\":1,\"posts_per_page\":\"10\",\"ignore_sticky_posts\":true,\"post_type\":\"loftocean_room\",\"post_status\":\"publish\",\"lang\":\"it\"},\"settings\":{\"layout\":\"zigzag\",\"columns\":false,\"metas\":[\"excerpt\",\"read_more_btn\",\"subtitle\",\"facilities\",\"label\"],\"page_layout\":\"\",\"subtitle_position\":\"before_title\",\"facility_limit\":\"\",\"pagination\":\"ajax-manual\",\"render_room_list\":\"yes\",\"archive_page\":\"elementor\"}}'>\n                        <div class=\"posts-wrapper cs-rooms-wrapper\">\n    <div class=\"post cs-room-item has-post-thumbnail\">            <div class=\"featured-img\">\n                <a href=\"https:\/\/hotel-life.hr\/it\/room\/camera-matrimoniale-superior-con-vista-mare-laterale-e-balcone\/\" aria-label=\"Room Featured Image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"520\" src=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999\" alt=\"hotel Life Rogoznica Croatia\" srcset=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg 780w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-300x200.jpg 300w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-1024x683.jpg 1024w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-768x512.jpg 768w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-1536x1024.jpg 1536w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-2048x1366.jpg 2048w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-1920x1280.jpg 1920w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-1440x960.jpg 1440w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-1200x800.jpg 1200w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-600x400.jpg 600w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-550x367.jpg 550w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-370x247.jpg 370w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-255x170.jpg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>                <\/a>            <\/div>\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/camera-matrimoniale-superior-con-vista-mare-laterale-e-balcone\/\">Camera Matrimoniale Superior con Vista Mare Laterale e Balcone<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Elegante Camera Superior di 26 m\u00b2 con comfort moderno, completata da un balcone privato arredato con vista mare laterale e un&#8217;atmosfera mediterranea tranquilla.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/camera-matrimoniale-superior-con-vista-mare-laterale-e-balcone\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n\n    <div class=\"post cs-room-item\">\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/family-suite\/\">Family Suite<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Spaziosa Family Suite con due camere da letto, zona giorno separata, vista mare e tutti i comfort necessari per un rilassante soggiorno in famiglia a Rogoznica.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/family-suite\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n\n    <div class=\"post cs-room-item\">\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/life-suite-vista-mare-con-balcone\/\">Life Suite Vista Mare con balcone<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Elegante Superior Room che offre 26 m\u00b2 di comfort moderno, completata da un balcone privato arredato con vista laterale sul mare e un&#8217;atmosfera mediterranea tranquilla.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/life-suite-vista-mare-con-balcone\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n\n    <div class=\"post cs-room-item\">\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/life-suite-con-vista-mare-laterale-e-balcone\/\">Life Suite con vista mare laterale e balcone<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Spaziosa Life Suite di 45\u201350 m\u00b2 con balcone privato, vista mare laterale e comfort raffinato per un soggiorno indimenticabile a Rogoznica e nella baia di Ze\u010devo.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/life-suite-con-vista-mare-laterale-e-balcone\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n\n    <div class=\"post cs-room-item has-post-thumbnail\">            <div class=\"featured-img\">\n                <a href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-deluxe-vista-mare-con-balcone\/\" aria-label=\"Room Featured Image\"><img decoding=\"async\" width=\"780\" height=\"519\" src=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-780x519.webp\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999\" alt=\"\" srcset=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-780x519.webp 780w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-300x200.webp 300w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-1024x681.webp 1024w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-768x511.webp 768w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-600x399.webp 600w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-550x366.webp 550w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-370x246.webp 370w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite-255x170.webp 255w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/DeluxeJuniorSuite.webp 1064w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>                <\/a>            <\/div>\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-deluxe-vista-mare-con-balcone\/\">Junior Suite Deluxe Vista Mare con balcone<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Spaziosa Junior Suite Deluxe di 40 m\u00b2 con balcone privato arredato, splendida vista sul mare ed eleganza raffinata per un soggiorno indimenticabile a Rogoznica.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-deluxe-vista-mare-con-balcone\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n\n    <div class=\"post cs-room-item\">\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-vista-mare-con-balcone\/\">Junior Suite Vista Mare con balcone<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Elegante Junior Suite di 26 m\u00b2 con balcone privato arredato, vista panoramica sul mare e comfort raffinato per un soggiorno rilassante nella baia di Ze\u010devo vicino a Rogoznica.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-vista-mare-con-balcone\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n\n    <div class=\"post cs-room-item has-post-thumbnail\">            <div class=\"featured-img\">\n                <a href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-con-vista-mare-laterale-e-balcone\/\" aria-label=\"Room Featured Image\"><img decoding=\"async\" width=\"780\" height=\"575\" src=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-780x575.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999\" alt=\"\" srcset=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-780x575.jpg 780w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-300x221.jpg 300w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-1024x755.jpg 1024w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-768x567.jpg 768w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-600x443.jpg 600w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-550x406.jpg 550w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-370x273.jpg 370w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1-255x188.jpg 255w, https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/JuniorSuite1.jpg 1037w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>                <\/a>            <\/div>\n        <div class=\"post-content cs-room-content\">\n            <header class=\"post-header item-header\">                <h2 class=\"post-title item-title\">\n                    <a href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-con-vista-mare-laterale-e-balcone\/\">Junior Suite con vista mare laterale e balcone<\/a>\n                <\/h2>            <div class=\"cs-room-basic-info\">\n                <ul>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-maximize\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-user-2\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bed-6\"><\/i><\/div>                                                    <\/li>                        <li>\n                            <div class=\"csrbi-icon\"><i class=\"flaticon flaticon-bathing\"><\/i><\/div>                                                    <\/li>                <\/ul>\n            <\/div>            <\/header>                <div class=\"post-excerpt item-excerpt\"><p>Elegante Camera Superior di 26 m\u00b2 dal comfort moderno, completata da un balcone privato arredato con vista mare laterale e un&#8217;atmosfera mediterranea tranquilla.<\/p>\n<\/div>                <footer class=\"post-footer item-footer\">                    <div class=\"more-btn\">\n                        <a class=\"read-more-btn button cs-btn-underline\" href=\"https:\/\/hotel-life.hr\/it\/room\/junior-suite-con-vista-mare-laterale-e-balcone\/\">\n                            <span>Discover More<\/span>\n                        <\/a>\n                    <\/div>\n                <\/footer>        <\/div>\n    <\/div>\n                        <\/div>                    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le Nostre Sistemazioni Camere &amp; Suite Goditi un soggiorno rilassante a Rogoznica con camere eleganti, comfort moderno e splendide viste sul mare Adriatico. Inizia il Tuo Soggiorno Confortevole Trova la Camera Perfetta per il Tuo Soggiorno Scopri 19 camere e suite elegantemente progettate nell&#8217;ambiente tranquillo della Baia di Ze\u010devo vicino a Rogoznica. Dalle confortevoli Superior &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"0","cozystay_single_page_custom_sticky_site_header":"0","cozystay_single_page_hide_page_title":"on","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-3141","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soggiorno - Hotel Life - Your Boutique Escape in Rogoznica, Croatia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel-life.hr\/it\/soggiorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soggiorno - Hotel Life - Your Boutique Escape in Rogoznica, Croatia\" \/>\n<meta property=\"og:description\" content=\"Le Nostre Sistemazioni Camere &amp; Suite Goditi un soggiorno rilassante a Rogoznica con camere eleganti, comfort moderno e splendide viste sul mare Adriatico. Inizia il Tuo Soggiorno Confortevole Trova la Camera Perfetta per il Tuo Soggiorno Scopri 19 camere e suite elegantemente progettate nell&#8217;ambiente tranquillo della Baia di Ze\u010devo vicino a Rogoznica. Dalle confortevoli Superior ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel-life.hr\/it\/soggiorno\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Life - Your Boutique Escape in Rogoznica, Croatia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T13:56:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/\",\"url\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/\",\"name\":\"Soggiorno - Hotel Life - Your Boutique Escape in Rogoznica, Croatia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotel-life.hr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/01_SuperiorSSB-780x520.jpg\",\"datePublished\":\"2023-05-08T10:31:29+00:00\",\"dateModified\":\"2026-07-22T13:56:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotel-life.hr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/01_SuperiorSSB-780x520.jpg\",\"contentUrl\":\"https:\\\/\\\/hotel-life.hr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/01_SuperiorSSB-780x520.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/soggiorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soggiorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/\",\"name\":\"Hotel Life - Your Boutique Escape in Rogoznica, Croatia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/#organization\",\"name\":\"Hotel Life - Your Boutique Escape in Rogoznica, Croatia\",\"url\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel-life.hr\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-hotelLife-1.png\",\"contentUrl\":\"https:\\\/\\\/hotel-life.hr\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-hotelLife-1.png\",\"width\":1535,\"height\":606,\"caption\":\"Hotel Life - Your Boutique Escape in Rogoznica, Croatia\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-life.hr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soggiorno - Hotel Life - Your Boutique Escape in Rogoznica, Croatia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel-life.hr\/it\/soggiorno\/","og_locale":"it_IT","og_type":"article","og_title":"Soggiorno - Hotel Life - Your Boutique Escape in Rogoznica, Croatia","og_description":"Le Nostre Sistemazioni Camere &amp; Suite Goditi un soggiorno rilassante a Rogoznica con camere eleganti, comfort moderno e splendide viste sul mare Adriatico. Inizia il Tuo Soggiorno Confortevole Trova la Camera Perfetta per il Tuo Soggiorno Scopri 19 camere e suite elegantemente progettate nell&#8217;ambiente tranquillo della Baia di Ze\u010devo vicino a Rogoznica. Dalle confortevoli Superior ...","og_url":"https:\/\/hotel-life.hr\/it\/soggiorno\/","og_site_name":"Hotel Life - Your Boutique Escape in Rogoznica, Croatia","article_modified_time":"2026-07-22T13:56:40+00:00","og_image":[{"url":"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel-life.hr\/it\/soggiorno\/","url":"https:\/\/hotel-life.hr\/it\/soggiorno\/","name":"Soggiorno - Hotel Life - Your Boutique Escape in Rogoznica, Croatia","isPartOf":{"@id":"https:\/\/hotel-life.hr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotel-life.hr\/it\/soggiorno\/#primaryimage"},"image":{"@id":"https:\/\/hotel-life.hr\/it\/soggiorno\/#primaryimage"},"thumbnailUrl":"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg","datePublished":"2023-05-08T10:31:29+00:00","dateModified":"2026-07-22T13:56:40+00:00","breadcrumb":{"@id":"https:\/\/hotel-life.hr\/it\/soggiorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel-life.hr\/it\/soggiorno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hotel-life.hr\/it\/soggiorno\/#primaryimage","url":"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg","contentUrl":"https:\/\/hotel-life.hr\/wp-content\/uploads\/2023\/05\/01_SuperiorSSB-780x520.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/hotel-life.hr\/it\/soggiorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotel-life.hr\/it\/"},{"@type":"ListItem","position":2,"name":"Soggiorno"}]},{"@type":"WebSite","@id":"https:\/\/hotel-life.hr\/it\/#website","url":"https:\/\/hotel-life.hr\/it\/","name":"Hotel Life - Your Boutique Escape in Rogoznica, Croatia","description":"","publisher":{"@id":"https:\/\/hotel-life.hr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel-life.hr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hotel-life.hr\/it\/#organization","name":"Hotel Life - Your Boutique Escape in Rogoznica, Croatia","url":"https:\/\/hotel-life.hr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hotel-life.hr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/cropped-hotelLife-1.png","contentUrl":"https:\/\/hotel-life.hr\/wp-content\/uploads\/2026\/06\/cropped-hotelLife-1.png","width":1535,"height":606,"caption":"Hotel Life - Your Boutique Escape in Rogoznica, Croatia"},"image":{"@id":"https:\/\/hotel-life.hr\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/pages\/3141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/comments?post=3141"}],"version-history":[{"count":3,"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/pages\/3141\/revisions"}],"predecessor-version":[{"id":3222,"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/pages\/3141\/revisions\/3222"}],"wp:attachment":[{"href":"https:\/\/hotel-life.hr\/it\/wp-json\/wp\/v2\/media?parent=3141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}